{"id":17807,"date":"2018-05-16T15:40:53","date_gmt":"2018-05-16T13:40:53","guid":{"rendered":"https:\/\/finzipasca.com\/?p=17807"},"modified":"2018-05-16T15:40:53","modified_gmt":"2018-05-16T13:40:53","slug":"daniele-finzi-pasca-invitato-speciale-al-telling-stories-fest","status":"publish","type":"post","link":"https:\/\/finzipasca.com\/it\/2018\/05\/daniele-finzi-pasca-invitato-speciale-al-telling-stories-fest\/","title":{"rendered":"Daniele Finzi Pasca invitato speciale al\u00a0Telling Stories Fest"},"content":{"rendered":"<p>Dal 23 al 25 aprile, <strong>Daniele Finzi Pasca \u00e8 stato invitato all&#8217;evento <em>Telling Stories Fest<\/em> a Mosca<\/strong>. Il Festival \u00e8 <strong>una piattaforma di dialogo fra tecnologia e creativit\u00e0<\/strong>. Hanno partecipato esperti del mondo del design, dell&#8217;arte, del teatro e della fotografia.<\/p>\n<p>Oltre a Daniele, hanno tenuto una relazione:<\/p>\n<ul>\n<li><strong>Darren Aronofsky<\/strong>: regista, sceneggiatore e produttore cinematografico<\/li>\n<li><strong>Oliviero Toscani<\/strong>: fotografo pubblicitario\u00a0di fama internazionale<\/li>\n<li><strong>Timur Bekmambetov<\/strong>: regista e produttore cinematografico<\/li>\n<li><strong>Henrik Vibskov<\/strong>: designer di moda<\/li>\n<li><strong>Konstantin Fam<\/strong>: regista<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 23 al 25 aprile, Daniele Finzi Pasca \u00e8 stato invitato all&#8217;evento Telling Stories Fest a Mosca. Il Festival \u00e8 una piattaforma di dialogo fra tecnologia e creativit\u00e0. Hanno partecipato esperti del mondo del design, dell&#8217;arte, del teatro e della fotografia. Oltre a Daniele, hanno tenuto una relazione: Darren Aronofsky: regista, sceneggiatore e produttore cinematografico Oliviero Toscani: fotografo pubblicitario\u00a0di fama internazionale Timur Bekmambetov: regista e produttore cinematografico Henrik Vibskov: designer di moda Konstantin Fam: regista &nbsp;<\/p>\n","protected":false},"author":27,"featured_media":17802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-17807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/posts\/17807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/comments?post=17807"}],"version-history":[{"count":0,"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/posts\/17807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/media\/17802"}],"wp:attachment":[{"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/media?parent=17807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/categories?post=17807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finzipasca.com\/it\/wp-json\/wp\/v2\/tags?post=17807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}